{"id":292,"date":"2022-07-15T04:21:30","date_gmt":"2022-07-15T04:21:30","guid":{"rendered":"http:\/\/stwards.com\/?post_type=services&#038;p=292"},"modified":"2025-02-07T10:21:24","modified_gmt":"2025-02-07T15:21:24","slug":"training-and-certifications","status":"publish","type":"services","link":"https:\/\/stwards.com\/es\/services\/training-and-certifications\/","title":{"rendered":"Capacitaciones y Certificaciones"},"content":{"rendered":"<h3>Capacitaciones y Certificaciones<\/h3>\n<h4>Nuestra compa\u00f1\u00eda<\/h4>\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/stwards.com\/wp-content\/uploads\/2022\/07\/barco-new-1.jpg\" alt=\"\" class=\"wp-image-359\" width=\"835\" height=\"556\" srcset=\"https:\/\/stwards.com\/wp-content\/uploads\/2022\/07\/barco-new-1.jpg 800w, https:\/\/stwards.com\/wp-content\/uploads\/2022\/07\/barco-new-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Licenciado por 10 a\u00f1os por la Autoridad Mar\u00edtima de Panam\u00e1 para realizar maniobras de amarre y desamarre en todo el pa\u00eds.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Nuestro equipo<\/h4>\n\n\n\n<ol class=\"wp-block-list\"><li>Nuestros tripulantes cuentan con m\u00e1s de 5 a\u00f1os de experiencia en el mercado del transporte de combustible a trav\u00e9s de barcazas flotantes.<\/li><li>Est\u00e1n familiarizados con las pol\u00edticas de navegaci\u00f3n segura, la pol\u00edtica ambiental y la pol\u00edtica de navegaci\u00f3n segura de alcohol y drogas de la empresa.<\/li><li>Gesti\u00f3n del Sistema de Gesti\u00f3n de Seguridad en espa\u00f1ol e ingl\u00e9s.<\/li><li>Conocimiento del Convenio sobre el trabajo mar\u00edtimo.<\/li><li>Certificaciones Internacionales. Test Marlin para comprobar el nivel de ingl\u00e9s<ul style=\"margin:0;\"><li>EcDYS Typer Certificado de competencia espec\u00edfico.<\/li><li>Conciencia cibern\u00e9tica.<\/li><\/ul><\/li><li>Certificados aprobados por la Autoridad Mar\u00edtima de Panam\u00e1 basados en el STCW seg\u00fan la  \n   Enmienda de Manila de 2017.<ul><li>Curso Avanzado de Petroleros.<\/li><li>Curso de Atenci\u00f3n M\u00e9dica.<\/li><li>Curso B\u00e1sico de Primeros Auxilios.<\/li><li>Curso B\u00e1sico de Extinci\u00f3n de Incendios.<\/li><li>Curso de Supervivencia en el Mar.<\/li><li>Concienciaci\u00f3n sobre el medio marino.<\/li><li>Curso de Oficial de Protecci\u00f3n de Buques.<\/li><li>Curso de Liderazgo y Trabajo en Equipo.<\/li><li>Curso de Gesti\u00f3n de Recursos bridge.<\/li><li>Certificado de Operador General para el Sistema Mundial de Socorro para la Seguridad Mar\u00edtima.<\/li><li>Uso operacional de los sistemas electr\u00f3nicos de visualizaci\u00f3n de cartas e informaci\u00f3n\nLucha contra incendios avanzada.<\/li><li>Extinci\u00f3n de incendios avanzada.<\/li><\/ul><\/li><li>Certificado de Competencia.<ul><li>Cuadernos para env\u00edos internacionales aprobados por la Autoridad Mar\u00edtima de Panam\u00e1.<\/li><li>Certificado emitido por la Autoridad del Canal de Panam\u00e1 como Operador menor de buques exento de practicaje.<\/li><\/ul><\/li><li>Evaluaciones m\u00e9dicas cada 2 a\u00f1os para la emisi\u00f3n de certificados m\u00e9dicos como gente de mar.<\/li><\/ol>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"573\" height=\"480\" src=\"http:\/\/stwards.com\/wp-content\/uploads\/2022\/07\/certification-1-1.png\" alt=\"\" class=\"wp-image-360\" srcset=\"https:\/\/stwards.com\/wp-content\/uploads\/2022\/07\/certification-1-1.png 573w, https:\/\/stwards.com\/wp-content\/uploads\/2022\/07\/certification-1-1-300x251.png 300w\" sizes=\"auto, (max-width: 573px) 100vw, 573px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"176\" src=\"http:\/\/stwards.com\/wp-content\/uploads\/2022\/07\/certification-2-1.png\" alt=\"\" class=\"wp-image-361\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"825\" height=\"1024\" src=\"http:\/\/stwards.com\/wp-content\/uploads\/2022\/07\/certification-3-1-825x1024.png\" alt=\"\" class=\"wp-image-362\" srcset=\"https:\/\/stwards.com\/wp-content\/uploads\/2022\/07\/certification-3-1-825x1024.png 825w, https:\/\/stwards.com\/wp-content\/uploads\/2022\/07\/certification-3-1-242x300.png 242w, https:\/\/stwards.com\/wp-content\/uploads\/2022\/07\/certification-3-1.png 1995w\" sizes=\"auto, (max-width: 825px) 100vw, 825px\" \/><\/figure>\n<\/div>\n<\/div>","protected":false},"featured_media":296,"parent":0,"menu_order":9,"template":"","categoria":[33],"class_list":["post-292","services","type-services","status-publish","has-post-thumbnail","hentry","categoria-ship-and-crew-management"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/stwards.com\/es\/wp-json\/wp\/v2\/services\/292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stwards.com\/es\/wp-json\/wp\/v2\/services"}],"about":[{"href":"https:\/\/stwards.com\/es\/wp-json\/wp\/v2\/types\/services"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stwards.com\/es\/wp-json\/wp\/v2\/media\/296"}],"wp:attachment":[{"href":"https:\/\/stwards.com\/es\/wp-json\/wp\/v2\/media?parent=292"}],"wp:term":[{"taxonomy":"categoria","embeddable":true,"href":"https:\/\/stwards.com\/es\/wp-json\/wp\/v2\/categoria?post=292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}